{"id":5372,"date":"2026-01-14T14:15:12","date_gmt":"2026-01-14T12:15:12","guid":{"rendered":"https:\/\/memoriedivetro.eu\/?post_type=product&#038;p=5372"},"modified":"2026-01-14T14:21:03","modified_gmt":"2026-01-14T12:21:03","slug":"set-di-foglie-in-vetro-di-murano-36","status":"publish","type":"product","link":"https:\/\/memoriedivetro.eu\/en\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/","title":{"rendered":"Set di foglie in vetro di Murano"},"content":{"rendered":"<p>Set composto da 2 foglie alte di ricambio in vetro di Murano.<br \/>\nColore marrone<\/p>\n<p>Misure:<\/p>\n<ul>\n<li>altezza 30 cm<\/li>\n<li>altezza gambo 16 cm<\/li>\n<li>profondit\u00e0 12 cm<\/li>\n<li>larghezza massima foglia 9 cm<\/li>\n<li>diametro bicchierino 16,5 circa (il bicchierino pu\u00f2 essere sostituito in base alle Vs esigenze)<\/li>\n<\/ul>\n<p>Il nostro magazzino \u00e8 fornito di molti pezzi di ricambio, contattaci per altri tipi di ricambi o per altre misure.<\/p>\n<p>La spedizione verr\u00e0 effettuata con imballo professionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Set foglie marroni in vetro di Murano<\/p>\n","protected":false},"featured_media":5373,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[533,419,593,541],"product_tag":[607,594,628,582,580,583,627,544,560,606,626,549,608,609,572,604,577,595,542,581,605,543,603],"class_list":{"0":"post-5372","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fogliemurano","7":"product_cat-ricambi-in-vetro-di-murano","8":"product_cat-set-foglie-alte-in-vetro-di-murano","9":"product_cat-stockmurano","10":"product_tag-2-foglie-blu","11":"product_tag-coppia-foglie-alte-in-vetro-di-murano","12":"product_tag-coppia-foglie-alte-murano","13":"product_tag-coppia-foglie-bianche","14":"product_tag-coppia-foglie-opalino-oro","15":"product_tag-coppia-foglie-seta-bianche","16":"product_tag-foglie-alte-in-vetro-di-murano","17":"product_tag-foglie-lampadari-murano","18":"product_tag-foglie-ricambio-murano","19":"product_tag-set-5-foglie-opalino-oro","20":"product_tag-set-foglie-alte","21":"product_tag-set-foglie-basse","22":"product_tag-set-foglie-blu-murano","23":"product_tag-set-foglie-cristallo-fume","24":"product_tag-set-foglie-cristallo-in-vetro-di-murano","25":"product_tag-set-foglie-cristallo-murano","26":"product_tag-set-foglie-fume-basse-murano","27":"product_tag-set-foglie-fume-in-vetro-di-murano","28":"product_tag-set-foglie-murano","29":"product_tag-set-foglie-opalino","30":"product_tag-set-foglie-opalino-oro","31":"product_tag-set-foglie-ricambio-murano","32":"product_tag-tris-foglie-cristallo","34":"first","35":"instock","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Set di foglie in vetro di Murano - Memorie di vetro<\/title>\n<meta name=\"description\" content=\"Entra nel magico e spettacolare mondo del vetro di Murano: immergiti nel mondo dell\u2019antico e del moderno, del vecchio e del nuovo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Set di foglie in vetro di Murano - Memorie di vetro\" \/>\n<meta property=\"og:description\" content=\"Entra nel magico e spettacolare mondo del vetro di Murano: immergiti nel mondo dell\u2019antico e del moderno, del vecchio e del nuovo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/\" \/>\n<meta property=\"og:site_name\" content=\"Memorie di vetro\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T12:21:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/\",\"url\":\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/\",\"name\":\"Set di foglie in vetro di Murano - Memorie di vetro\",\"isPartOf\":{\"@id\":\"https:\/\/memoriedivetro.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg\",\"datePublished\":\"2026-01-14T12:15:12+00:00\",\"dateModified\":\"2026-01-14T12:21:03+00:00\",\"description\":\"Entra nel magico e spettacolare mondo del vetro di Murano: immergiti nel mondo dell\u2019antico e del moderno, del vecchio e del nuovo.\",\"breadcrumb\":{\"@id\":\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#primaryimage\",\"url\":\"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg\",\"contentUrl\":\"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\/\/memoriedivetro.eu\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Set di foglie in vetro di Murano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/memoriedivetro.eu\/#website\",\"url\":\"https:\/\/memoriedivetro.eu\/\",\"name\":\"Memorie di vetro\",\"description\":\"Entra nel magico e spettacolare mondo del vetro di Murano\",\"alternateName\":\"Memorie di Vetro\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/memoriedivetro.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Set di foglie in vetro di Murano - Memorie di vetro","description":"Entra nel magico e spettacolare mondo del vetro di Murano: immergiti nel mondo dell\u2019antico e del moderno, del vecchio e del nuovo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/","og_locale":"en_US","og_type":"article","og_title":"Set di foglie in vetro di Murano - Memorie di vetro","og_description":"Entra nel magico e spettacolare mondo del vetro di Murano: immergiti nel mondo dell\u2019antico e del moderno, del vecchio e del nuovo.","og_url":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/","og_site_name":"Memorie di vetro","article_modified_time":"2026-01-14T12:21:03+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/","url":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/","name":"Set di foglie in vetro di Murano - Memorie di vetro","isPartOf":{"@id":"https:\/\/memoriedivetro.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#primaryimage"},"image":{"@id":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#primaryimage"},"thumbnailUrl":"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg","datePublished":"2026-01-14T12:15:12+00:00","dateModified":"2026-01-14T12:21:03+00:00","description":"Entra nel magico e spettacolare mondo del vetro di Murano: immergiti nel mondo dell\u2019antico e del moderno, del vecchio e del nuovo.","breadcrumb":{"@id":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#primaryimage","url":"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg","contentUrl":"https:\/\/memoriedivetro.eu\/wp-content\/uploads\/IMG_7859-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/memoriedivetro.eu\/prodotto\/set-di-foglie-in-vetro-di-murano-36\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/memoriedivetro.eu\/negozio\/"},{"@type":"ListItem","position":2,"name":"Set di foglie in vetro di Murano"}]},{"@type":"WebSite","@id":"https:\/\/memoriedivetro.eu\/#website","url":"https:\/\/memoriedivetro.eu\/","name":"Memorie di vetro","description":"Entra nel magico e spettacolare mondo del vetro di Murano","alternateName":"Memorie di Vetro","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/memoriedivetro.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/product\/5372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/comments?post=5372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/media\/5373"}],"wp:attachment":[{"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/media?parent=5372"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/product_brand?post=5372"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/product_cat?post=5372"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/memoriedivetro.eu\/en\/wp-json\/wp\/v2\/product_tag?post=5372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}